{"id":5239,"date":"2006-02-08T17:23:00","date_gmt":"2006-02-08T17:23:00","guid":{"rendered":"https:\/\/inveske.co.uk\/filhos\/"},"modified":"2006-02-08T17:23:00","modified_gmt":"2006-02-08T17:23:00","slug":"filhos","status":"publish","type":"post","link":"https:\/\/www.mariliacoutinho.com\/pt-br\/filhos\/","title":{"rendered":"Filhos"},"content":{"rendered":"<p>Hoje entrei na comunidade-orkut que a Roberta, filha da atleta Regina Vilella, fez para ela (http:\/\/www.orkut.com\/Community.aspx?cmm=5513345 ). A introdu\u00e7\u00e3o da comunidade \u00e9 muito interessante. Por que a Regina mereceria uma comunidade-orkut s\u00f3 para ela? A Roberta responde: porque \u00e9 uma super m\u00e3e, amiga, divertida, tolerante, cozinha bem&#8230; uma por\u00e7\u00e3o de adjetivos legais. Em nenhum momento ela diz: porque ela teve tais e tais t\u00edtulos, foi \u00e0s Olimp\u00edadas de Moscou, colecionou n\u00e3o sei quantas gl\u00f3rias&#8230; Nada disso. No fundo, o que ela quis dizer, eu senti, foi a vontade de transmitir aos outros a id\u00e9ia de que aquela mulher \u00e9 a m\u00e3e dela, \u00e9 importante para ela, faz comidas que a confortam, esteve e est\u00e1 do lado dela naqueles momentos complicados em que todos n\u00f3s somos um pouco fr\u00e1geis.<br \/>\nEu li e fiquei emocionada. Acho que \u00e9 tudo que uma m\u00e3e pode querer \u2013 depois disso, tudo \u00e9 lucro. N\u00e3o h\u00e1 gl\u00f3ria, p\u00f3dio, pr\u00eamio, reconhecimento de m\u00e9rito, grana ou poder que se compare a conferir que satisfazemos quem mais nos importa no universo: nosso filho. E n\u00e3o o satisfazemos pela medalha, e sim por um picadinho com batata, salsicha com pur\u00ea, torta de galinha ou pudim de leite.<br \/>\nN\u00e3o existe satisfa\u00e7\u00e3o que se compare ao sorriso do seu filho quando olha para voc\u00ea e abre os bracinhos quando voc\u00ea aparece no port\u00e3o do jardim-da-inf\u00e2ncia; quando come o seu pudim ou quando encontra voc\u00ea no quarto, dormindo.<br \/>\n\u201cEstar l\u00e1\u201d para um filho \u00e9 um pouco como comer. \u00c9 quase satisfazer uma necessidade fisiol\u00f3gica.<br \/>\nAcho que isso deve ser parte do motivo do sucesso da nossa esp\u00e9cie.<br \/>\nEssa analogia corporal \u00e9 muito mais forte do que se imagina.<br \/>\nEu tenho uma desordem complicada que faz minha percep\u00e7\u00e3o do mundo variar bastante. H\u00e1 momentos em que tudo perde um pouco o sentido. A primeira vez que passei um longo per\u00edodo de tempo sem nenhuma perda de sentido foi quando estive gr\u00e1vida da Mel. Foram nove meses de pleno sentido. Ent\u00e3o ela nasceu e por tr\u00eas dias eu tive que me ajustar a um mundo em que eu n\u00e3o era mais o mundo dela, em que meu corpo havia se particionado, em que eu havia deixado de ser fisicamente dois-em-um. Foram tr\u00eas dias complicados. Mas logo foram superados pelo fato de que de tr\u00eas em tr\u00eas horas uma grande parte de mim se transformava nela: minha filha apenas mamou por seis meses e mamou de fato por um ano. Parte da minha fisiologia continuava sendo \u201cproduzir Mel\u201d.<br \/>\nMas um dia ela decidiu n\u00e3o mais mamar meu leite.<br \/>\nNesse dia voltei a ter meus ciclos de falta de sentido.<br \/>\nExiste algo profundamente corporal na condi\u00e7\u00e3o de m\u00e3e que homem nenhum ou pessoa nenhuma que n\u00e3o pariu \u00e9 capaz de entender. Um filho \u00e9 sempre uma combina\u00e7\u00e3o paradoxal de \u201cvoc\u00ea\u201d com um \u201cn\u00e3o-voc\u00ea\u201d. E a parte \u201cvoc\u00ea\u201d \u00e9 sempre voc\u00ea. \u00c9 sempre um peda\u00e7o do seu corpo que sai andando por a\u00ed, pega \u00f4nibus, faz aula de clarinete, escreve poesia e viaja para o Mato Grosso.<br \/>\nEm certos momentos, hoje, as coisas ficam ainda naquele limbo de sentido: v\u00e3o perdendo&#8230; quase perdem&#8230; mas a\u00ed a Mel se materializa na minha frente ou ou\u00e7o a voz dela no telefone e as pe\u00e7as do quebra-cabe\u00e7as voltam aos seus lugares.<br \/>\nNa semana passada, minha amiga Fl\u00e1via tentou me ensinar a, nesses momentos, buscar a Mel sem necessariamente busc\u00e1-la concretamente. Recuper\u00e1-la internamente. Porque a mem\u00f3ria f\u00edsica da exist\u00eancia dela \u00e9 permanente e pode ser chamada a qualquer momento. \u00c9 mais benigno. Menos parasit\u00e1rio. Estou trabalhando nisso e acho que vou conseguir.<br \/>\nEla \u00e9 esse peda\u00e7o de mim que, por ser afastado, por ter autonomia, por ser o melhor de todos, n\u00e3o \u00e9 afetado pelo que quer que corroa todo o sentido do que est\u00e1 em volta.<\/p>\n<p>Marilia <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\"><b><font face=\"Georgia\" size=\"1\"><br \/>\n<a href=\"http:\/\/www.bodystuff.org\/\">BodyStuff<\/a><\/font><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje entrei na comunidade-orkut que a Roberta, filha da atleta Regina Vilella, fez para ela (http:\/\/www.orkut.com\/Community.aspx?cmm=5513345 ). A introdu\u00e7\u00e3o da comunidade \u00e9 muito interessante. Por que a Regina mereceria uma comunidade-orkut s\u00f3 para ela? A Roberta responde: porque \u00e9 uma super m\u00e3e, amiga, divertida, tolerante, cozinha bem&#8230; uma por\u00e7\u00e3o de adjetivos legais. Em nenhum momento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/posts\/5239"}],"collection":[{"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/comments?post=5239"}],"version-history":[{"count":0,"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/posts\/5239\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/media?parent=5239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/categories?post=5239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mariliacoutinho.com\/pt-br\/wp-json\/wp\/v2\/tags?post=5239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}